{"id":3660,"date":"2023-07-18T17:09:25","date_gmt":"2023-07-18T17:09:25","guid":{"rendered":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/?page_id=3660"},"modified":"2025-02-13T18:52:02","modified_gmt":"2025-02-13T18:52:02","slug":"careers","status":"publish","type":"page","link":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/","title":{"rendered":"Careers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3660\" class=\"elementor elementor-3660\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cccdcfd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cccdcfd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b12cfa\" data-id=\"5b12cfa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5f5e84 elementor-widget elementor-widget-heading\" data-id=\"b5f5e84\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Start a Fulfilling Career at Senior Living Job Application<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e3891e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e3891e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2597c7c\" data-id=\"2597c7c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aedbfc7 elementor-widget elementor-widget-text-editor\" data-id=\"aedbfc7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>If you are interested in working at The Goldton at Adelaide please complete the application below. We will contact you if your skills match any of our open positions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb8b1dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb8b1dc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4fc3825\" data-id=\"4fc3825\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3703c57 uael-wpf-input-size-lg uael-wpf-check-yes uael-wpf-btn-size-md uael-wpf-style-box uael-wpf-button-left uael-wpf-highlight-style-default elementor-widget elementor-widget-uael-wpf-styler\" data-id=\"3703c57\" data-element_type=\"widget\" data-settings=\"{&quot;wpf_input_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;10&quot;,&quot;right&quot;:&quot;10&quot;,&quot;bottom&quot;:&quot;10&quot;,&quot;left&quot;:&quot;10&quot;,&quot;isLinked&quot;:true},&quot;wpf_button_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;10&quot;,&quot;right&quot;:&quot;40&quot;,&quot;bottom&quot;:&quot;10&quot;,&quot;left&quot;:&quot;40&quot;,&quot;isLinked&quot;:false},&quot;btn_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;0&quot;,&quot;right&quot;:&quot;0&quot;,&quot;bottom&quot;:&quot;0&quot;,&quot;left&quot;:&quot;0&quot;,&quot;isLinked&quot;:true},&quot;form_fields_margin&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;form_label_margin_bottom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;form_desc_margin_top&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;submit_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;form_fields_margin_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:5,&quot;sizes&quot;:[]},&quot;wpf_input_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;wpf_input_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;wpf_input_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;0&quot;,&quot;right&quot;:&quot;0&quot;,&quot;bottom&quot;:&quot;0&quot;,&quot;left&quot;:&quot;0&quot;,&quot;isLinked&quot;:true},&quot;wpf_input_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;wpf_input_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;wpf_button_align&quot;:&quot;left&quot;,&quot;wpf_button_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;wpf_button_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;btn_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;btn_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;form_fields_margin_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;form_label_margin_bottom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;form_label_margin_bottom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;form_desc_margin_top_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;form_desc_margin_top_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;check_radio_items_spacing&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;check_radio_items_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;check_radio_items_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;submit_spacing_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;submit_spacing_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"uael-wpf-styler.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class = \"uael-wpf-container\">\n\t\t\t\t\t\t<div class = \"uael-wpf uael-wpf-style elementor-clickable\">\n\t\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-3673\"><form id=\"wpforms-form-3673\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"3673\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/pages\/3660\" data-token=\"f7e1f961fc72a99039c4914d43cd55e7\" data-token-time=\"1788352330\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-page-indicator progress\" data-indicator=\"progress\" data-indicator-color=\"#b33a6e\" data-scroll=\"1\"><span class=\"wpforms-page-indicator-page-title\" data-page-1-title=\"About You\">About You<\/span><span class=\"wpforms-page-indicator-page-title-sep\" > - <\/span><span class=\"wpforms-page-indicator-steps\">Step <span class=\"wpforms-page-indicator-steps-current\">1<\/span> of 2<\/span><div class=\"wpforms-page-indicator-page-progress-wrap\"><div class=\"wpforms-page-indicator-page-progress\" style=\"width:50%;background-color:#b33a6e\"><\/div><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \" data-page=\"1\"><div id=\"wpforms-3673-field_5-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"5\"><\/div><div id=\"wpforms-3673-field_7-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_7\">Job Interest<\/label><input type=\"text\" id=\"wpforms-3673-field_7\" class=\"wpforms-field-large\" name=\"wpforms[fields][7]\" ><\/div><div id=\"wpforms-3673-field_8-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"8\"><label class=\"wpforms-field-label\">Your Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-3673-field_8\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][8][first]\" placeholder=\"First Name\" required><label for=\"wpforms-3673-field_8\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-3673-field_8-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][8][last]\" placeholder=\"Last Name\" required><label for=\"wpforms-3673-field_8-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-3673-field_9-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_9\">Your Phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-3673-field_9\" class=\"wpforms-field-large wpforms-field-required wpforms-masked-input\" data-inputmask=\"&#039;mask&#039;: &#039;(999) 999-9999&#039;\" data-rule-us-phone-field=\"true\" data-inputmask-inputmode=\"tel\" name=\"wpforms[fields][9]\" aria-label=\"Your Phone\" required><\/div><div id=\"wpforms-3673-field_10-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_10\">Your Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-3673-field_10\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][10]\" spellcheck=\"false\" required><\/div>\t\t<div id=\"wpforms-3673-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-3673-field_1\" >until: from: desired:<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-3673-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-3673-field_11-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_11\">I prefer to be contacted: <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-3673-field_11\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][11]\" required=\"required\"><option value=\"By phone\"  class=\"choice-1 depth-1\"  >By phone<\/option><option value=\"By email\"  class=\"choice-2 depth-1\"  >By email<\/option><\/select><\/div><div id=\"wpforms-3673-field_12-container\" class=\"wpforms-field wpforms-field-address\" data-field-id=\"12\"><label class=\"wpforms-field-label\">Current Address<\/label><div class=\"wpforms-field-row wpforms-field-large\"><div ><input type=\"text\" id=\"wpforms-3673-field_12\" class=\"wpforms-field-address-address1\" name=\"wpforms[fields][12][address1]\" ><label for=\"wpforms-3673-field_12\" class=\"wpforms-field-sublabel after\">Address Line 1<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div ><input type=\"text\" id=\"wpforms-3673-field_12-address2\" class=\"wpforms-field-address-address2\" name=\"wpforms[fields][12][address2]\" ><label for=\"wpforms-3673-field_12-address2\" class=\"wpforms-field-sublabel after\">Address Line 2<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-3673-field_12-city\" class=\"wpforms-field-address-city\" name=\"wpforms[fields][12][city]\" ><label for=\"wpforms-3673-field_12-city\" class=\"wpforms-field-sublabel after\">City<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><select id=\"wpforms-3673-field_12-state\" class=\"wpforms-field-address-state\" name=\"wpforms[fields][12][state]\" ><option class=\"placeholder\" value=\"\" selected disabled>--- Select state ---<\/option><option value=\"AL\" >Alabama<\/option><option value=\"AK\" >Alaska<\/option><option value=\"AZ\" >Arizona<\/option><option value=\"AR\" >Arkansas<\/option><option value=\"CA\" >California<\/option><option value=\"CO\" >Colorado<\/option><option value=\"CT\" >Connecticut<\/option><option value=\"DE\" >Delaware<\/option><option value=\"DC\" >District of Columbia<\/option><option value=\"FL\" >Florida<\/option><option value=\"GA\" >Georgia<\/option><option value=\"HI\" >Hawaii<\/option><option value=\"ID\" >Idaho<\/option><option value=\"IL\" >Illinois<\/option><option value=\"IN\" >Indiana<\/option><option value=\"IA\" >Iowa<\/option><option value=\"KS\" >Kansas<\/option><option value=\"KY\" >Kentucky<\/option><option value=\"LA\" >Louisiana<\/option><option value=\"ME\" >Maine<\/option><option value=\"MD\" >Maryland<\/option><option value=\"MA\" >Massachusetts<\/option><option value=\"MI\" >Michigan<\/option><option value=\"MN\" >Minnesota<\/option><option value=\"MS\" >Mississippi<\/option><option value=\"MO\" >Missouri<\/option><option value=\"MT\" >Montana<\/option><option value=\"NE\" >Nebraska<\/option><option value=\"NV\" >Nevada<\/option><option value=\"NH\" >New Hampshire<\/option><option value=\"NJ\" >New Jersey<\/option><option value=\"NM\" >New Mexico<\/option><option value=\"NY\" >New York<\/option><option value=\"NC\" >North Carolina<\/option><option value=\"ND\" >North Dakota<\/option><option value=\"OH\" >Ohio<\/option><option value=\"OK\" >Oklahoma<\/option><option value=\"OR\" >Oregon<\/option><option value=\"PA\" >Pennsylvania<\/option><option value=\"RI\" >Rhode Island<\/option><option value=\"SC\" >South Carolina<\/option><option value=\"SD\" >South Dakota<\/option><option value=\"TN\" >Tennessee<\/option><option value=\"TX\" >Texas<\/option><option value=\"UT\" >Utah<\/option><option value=\"VT\" >Vermont<\/option><option value=\"VA\" >Virginia<\/option><option value=\"WA\" >Washington<\/option><option value=\"WV\" >West Virginia<\/option><option value=\"WI\" >Wisconsin<\/option><option value=\"WY\" >Wyoming<\/option><\/select><label for=\"wpforms-3673-field_12-state\" class=\"wpforms-field-sublabel after\">State<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-3673-field_12-postal\" class=\"wpforms-field-address-postal wpforms-masked-input\" data-inputmask-mask=\"(99999)|(99999-9999)\" data-inputmask-keepstatic=\"true\" data-rule-inputmask-incomplete=\"1\" name=\"wpforms[fields][12][postal]\" ><label for=\"wpforms-3673-field_12-postal\" class=\"wpforms-field-sublabel after\">Zip Code<\/label><\/div><\/div><\/div><div id=\"wpforms-3673-field_13-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_13\">Emergency Contact Name and Number<\/label><textarea id=\"wpforms-3673-field_13\" class=\"wpforms-field-medium\" name=\"wpforms[fields][13]\" ><\/textarea><\/div><div id=\"wpforms-3673-field_14-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"14\"><label class=\"wpforms-field-label\">Are you over 18 years of age? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-3673-field_14\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_14_1\" name=\"wpforms[fields][14]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_14_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_14_2\" name=\"wpforms[fields][14]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_14_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_15-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"15\"><label class=\"wpforms-field-label\">If yes, can you provide proof of employment eligibility?<\/label><ul id=\"wpforms-3673-field_15\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_15_1\" name=\"wpforms[fields][15]\" value=\"Yes\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_15_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_15_2\" name=\"wpforms[fields][15]\" value=\"No\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_15_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_16-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"16\"><label class=\"wpforms-field-label\">If hired, are you able to furnish proof that you are legally qualified to work in the United States? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-3673-field_16\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_16_1\" name=\"wpforms[fields][16]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_16_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_16_2\" name=\"wpforms[fields][16]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_16_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_17-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline wpforms-conditional-trigger\" data-field-id=\"17\"><label class=\"wpforms-field-label\">Do you have a valid driver&#039;s license? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-3673-field_17\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_17_1\" name=\"wpforms[fields][17]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_17_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_17_2\" name=\"wpforms[fields][17]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_17_2\">No<\/label><\/li><\/ul><div class=\"wpforms-field-description\">To comply with the Immigration Reform and Control Act of 1986, if you are hired you will be required to provide documents to establish your identity and your authorization to be employed in the United States. Such documents will be required within the first three business days following your hire, or upon your first work day if your employment period will be less than three days.<\/div><\/div><div id=\"wpforms-3673-field_18-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"18\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_18\">License number\/issuing state:<\/label><input type=\"text\" id=\"wpforms-3673-field_18\" class=\"wpforms-field-medium\" name=\"wpforms[fields][18]\" ><\/div><div id=\"wpforms-3673-field_19-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"19\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_19\">How did you find out about this employment opportunity?<\/label><textarea id=\"wpforms-3673-field_19\" class=\"wpforms-field-medium\" name=\"wpforms[fields][19]\" ><\/textarea><\/div><div id=\"wpforms-3673-field_20-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"20\"><label class=\"wpforms-field-label\">Type of employment desired: <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-3673-field_20\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-3673-field_20_1\" name=\"wpforms[fields][20][]\" value=\"Fulltime (32 hrs\/week or more)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_20_1\">Fulltime (32 hrs\/week or more)<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-3673-field_20_2\" name=\"wpforms[fields][20][]\" value=\"Part-time (less than 32 hrs\/week)\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_20_2\">Part-time (less than 32 hrs\/week)<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_21-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"21\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_21\">What shifts are you available? Are there days or times when you are unable to work or prefer to not work? How many hours would you like to work per week? Please explain. <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-3673-field_21\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][21]\" required><\/textarea><\/div><div id=\"wpforms-3673-field_22-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"22\"><label class=\"wpforms-field-label\">Are you able to perform the functions of this job, with or without reasonable accommodation? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-3673-field_22\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_22_1\" name=\"wpforms[fields][22]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_22_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_22_2\" name=\"wpforms[fields][22]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_22_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_23-container\" class=\"wpforms-field wpforms-field-radio wpforms-conditional-trigger\" data-field-id=\"23\"><label class=\"wpforms-field-label\">Have you ever been convicted of a crime? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-3673-field_23\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_23_1\" name=\"wpforms[fields][23]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_23_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_23_2\" name=\"wpforms[fields][23]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_23_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_24-container\" class=\"wpforms-field wpforms-field-textarea wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"24\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_24\">Please explain<\/label><textarea id=\"wpforms-3673-field_24\" class=\"wpforms-field-medium\" name=\"wpforms[fields][24]\" ><\/textarea><\/div><div id=\"wpforms-3673-field_25-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"25\"><h3 id=\"wpforms-3673-field_25\">High School\/GED<\/h3><\/div><div id=\"wpforms-3673-field_26-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"26\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_26\">High School\/GED (Name and Location): <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3673-field_26\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][26]\" required><\/div><div id=\"wpforms-3673-field_27-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"27\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_27\">Number of years completed: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3673-field_27\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][27]\" required><\/div><div id=\"wpforms-3673-field_28-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"28\"><label class=\"wpforms-field-label\">Did you graduate? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-3673-field_28\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_28_1\" name=\"wpforms[fields][28]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_28_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_28_2\" name=\"wpforms[fields][28]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_28_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_29-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"29\"><h3 id=\"wpforms-3673-field_29\">College\/University<\/h3><\/div><div id=\"wpforms-3673-field_30-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"30\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_30\">College\/University (Name and Location):<\/label><input type=\"text\" id=\"wpforms-3673-field_30\" class=\"wpforms-field-large\" name=\"wpforms[fields][30]\" ><\/div><div id=\"wpforms-3673-field_31-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"31\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_31\">Degree\/Major:<\/label><input type=\"text\" id=\"wpforms-3673-field_31\" class=\"wpforms-field-large\" name=\"wpforms[fields][31]\" ><\/div><div id=\"wpforms-3673-field_32-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"32\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_32\">Number of years completed:<\/label><input type=\"text\" id=\"wpforms-3673-field_32\" class=\"wpforms-field-large\" name=\"wpforms[fields][32]\" ><\/div><div id=\"wpforms-3673-field_33-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"33\"><label class=\"wpforms-field-label\">Did you graduate?<\/label><ul id=\"wpforms-3673-field_33\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_33_1\" name=\"wpforms[fields][33]\" value=\"Yes\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_33_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_33_2\" name=\"wpforms[fields][33]\" value=\"No\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_33_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_34-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"34\"><h3 id=\"wpforms-3673-field_34\">Additional Education<\/h3><\/div><div id=\"wpforms-3673-field_35-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"35\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_35\">Additional Education or Other (Name and Location):<\/label><input type=\"text\" id=\"wpforms-3673-field_35\" class=\"wpforms-field-large\" name=\"wpforms[fields][35]\" ><\/div><div id=\"wpforms-3673-field_36-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"36\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_36\">Degree\/Major:<\/label><input type=\"text\" id=\"wpforms-3673-field_36\" class=\"wpforms-field-large\" name=\"wpforms[fields][36]\" ><\/div><div id=\"wpforms-3673-field_37-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"37\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_37\">Number of years completed:<\/label><input type=\"text\" id=\"wpforms-3673-field_37\" class=\"wpforms-field-large\" name=\"wpforms[fields][37]\" ><\/div><div id=\"wpforms-3673-field_38-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"38\"><label class=\"wpforms-field-label\">Did you graduate?<\/label><ul id=\"wpforms-3673-field_38\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_38_1\" name=\"wpforms[fields][38]\" value=\"Yes\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_38_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_38_2\" name=\"wpforms[fields][38]\" value=\"No\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_38_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_39-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"39\"><label class=\"wpforms-field-label\">Highest degree earned:<\/label><ul id=\"wpforms-3673-field_39\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_39_1\" name=\"wpforms[fields][39]\" value=\"High School\/GED\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_39_1\">High School\/GED<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_39_2\" name=\"wpforms[fields][39]\" value=\"Associate\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_39_2\">Associate<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_39_3\" name=\"wpforms[fields][39]\" value=\"Bachelor\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_39_3\">Bachelor<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_39_4\" name=\"wpforms[fields][39]\" value=\"Master\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_39_4\">Master<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_39_5\" name=\"wpforms[fields][39]\" value=\"Doctorate\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_39_5\">Doctorate<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_40-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"40\"><h3 id=\"wpforms-3673-field_40\">Skills<\/h3><\/div><div id=\"wpforms-3673-field_41-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"41\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_41\">Professional Licensures\/Certifications<\/label><textarea id=\"wpforms-3673-field_41\" class=\"wpforms-field-medium\" name=\"wpforms[fields][41]\" ><\/textarea><div class=\"wpforms-field-description\">Enter License Type, Issuing State, License Number and Expiration Date.<\/div><\/div><div id=\"wpforms-3673-field_42-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"42\"><div id=\"wpforms-3673-field_42\">Note: If you are hired for a position that requires state or national registration or certification, you must furnish Atlas Senior Living with current proof of certification or registration. <\/div><\/div><div id=\"wpforms-3673-field_43-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"43\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_43\">Skills &amp; Qualifications<\/label><textarea id=\"wpforms-3673-field_43\" class=\"wpforms-field-medium\" name=\"wpforms[fields][43]\" ><\/textarea><div class=\"wpforms-field-description\">Please list unique job-related skills and qualifications acquired from current\/previous employment or other experiences.<\/div><\/div><div id=\"wpforms-3673-field_44-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"44\"><div id=\"wpforms-3673-field_44\"><p>Please specify your complete full-time and part-time employment history, including self-employment. Begin with your most recent employer. All employers including your current employer may be contacted to verify the information you provide.<\/p><\/div><\/div><div id=\"wpforms-3673-field_4-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"4\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-next\" data-action=\"next\" data-page=\"1\" data-formid=\"3673\" disabled>Next<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2 last \" data-page=\"2\" style=\"display:none;\"><div id=\"wpforms-3673-field_45-container\" class=\"wpforms-field wpforms-field-radio wpforms-list-inline\" data-field-id=\"45\"><label class=\"wpforms-field-label\">May we contact your current employer prior to an offer of employment? <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-3673-field_45\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_45_1\" name=\"wpforms[fields][45]\" value=\"Yes\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_45_1\">Yes<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-3673-field_45_2\" name=\"wpforms[fields][45]\" value=\"No\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_45_2\">No<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_46-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"46\"><h3 id=\"wpforms-3673-field_46\">Employer 1<\/h3><\/div><div id=\"wpforms-3673-field_47-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"47\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_47\">Employer Name: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3673-field_47\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][47]\" required><\/div><div id=\"wpforms-3673-field_48-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"48\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_48\">City\/State:<\/label><input type=\"text\" id=\"wpforms-3673-field_48\" class=\"wpforms-field-large\" name=\"wpforms[fields][48]\" ><\/div><div id=\"wpforms-3673-field_49-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"49\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_49\">Supervisor&#039;s Name:<\/label><input type=\"text\" id=\"wpforms-3673-field_49\" class=\"wpforms-field-large\" name=\"wpforms[fields][49]\" ><\/div><div id=\"wpforms-3673-field_50-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"50\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_50\">Supervisor&#039;s Title:<\/label><input type=\"text\" id=\"wpforms-3673-field_50\" class=\"wpforms-field-large\" name=\"wpforms[fields][50]\" ><\/div><div id=\"wpforms-3673-field_51-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"51\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_51\">Supervisor&#039;s Phone:<\/label><input type=\"tel\" id=\"wpforms-3673-field_51\" class=\"wpforms-field-large wpforms-masked-input\" data-inputmask=\"&#039;mask&#039;: &#039;(999) 999-9999&#039;\" data-rule-us-phone-field=\"true\" data-inputmask-inputmode=\"tel\" name=\"wpforms[fields][51]\" aria-label=\"Supervisor&#039;s Phone:\" ><\/div><div id=\"wpforms-3673-field_53-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"53\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_53\">Employed from: <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-3673-field_53\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-large\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][53][date]\" placeholder=\"Start Date\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-3673-field_54-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"54\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_54\">Employed until <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-3673-field_54\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-large\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][54][date]\" placeholder=\"End Date\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-3673-field_55-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"55\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_55\">Starting Salary:<\/label><input type=\"text\" id=\"wpforms-3673-field_55\" class=\"wpforms-field-large\" name=\"wpforms[fields][55]\" ><\/div><div id=\"wpforms-3673-field_56-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"56\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_56\">Ending Salary:<\/label><input type=\"text\" id=\"wpforms-3673-field_56\" class=\"wpforms-field-large\" name=\"wpforms[fields][56]\" ><\/div><div id=\"wpforms-3673-field_57-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"57\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_57\">Your Position and Job Responsibilities:<\/label><textarea id=\"wpforms-3673-field_57\" class=\"wpforms-field-medium\" name=\"wpforms[fields][57]\" ><\/textarea><\/div><div id=\"wpforms-3673-field_58-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"58\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_58\">Reason for Leaving:<\/label><input type=\"text\" id=\"wpforms-3673-field_58\" class=\"wpforms-field-large\" name=\"wpforms[fields][58]\" ><\/div><div id=\"wpforms-3673-field_59-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"59\"><label class=\"wpforms-field-label wpforms-label-hide\">Current Employer<\/label><ul id=\"wpforms-3673-field_59\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-3673-field_59_1\" name=\"wpforms[fields][59][]\" value=\"This is my current employer\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3673-field_59_1\">This is my current employer<\/label><\/li><\/ul><\/div><div id=\"wpforms-3673-field_60-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"60\"><h3 id=\"wpforms-3673-field_60\">Employer 2<\/h3><\/div><div id=\"wpforms-3673-field_61-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"61\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_61\">Employer Name:<\/label><input type=\"text\" id=\"wpforms-3673-field_61\" class=\"wpforms-field-large\" name=\"wpforms[fields][61]\" ><\/div><div id=\"wpforms-3673-field_62-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"62\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_62\">City\/State:<\/label><input type=\"text\" id=\"wpforms-3673-field_62\" class=\"wpforms-field-large\" name=\"wpforms[fields][62]\" ><\/div><div id=\"wpforms-3673-field_63-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"63\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_63\">Supervisor&#039;s Name:<\/label><input type=\"text\" id=\"wpforms-3673-field_63\" class=\"wpforms-field-large\" name=\"wpforms[fields][63]\" ><\/div><div id=\"wpforms-3673-field_64-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"64\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_64\">Supervisor&#039;s Title:<\/label><input type=\"text\" id=\"wpforms-3673-field_64\" class=\"wpforms-field-large\" name=\"wpforms[fields][64]\" ><\/div><div id=\"wpforms-3673-field_65-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"65\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_65\">Supervisor&#039;s Phone:<\/label><input type=\"tel\" id=\"wpforms-3673-field_65\" class=\"wpforms-field-large wpforms-masked-input\" data-inputmask=\"&#039;mask&#039;: &#039;(999) 999-9999&#039;\" data-rule-us-phone-field=\"true\" data-inputmask-inputmode=\"tel\" name=\"wpforms[fields][65]\" aria-label=\"Supervisor&#039;s Phone:\" ><\/div><div id=\"wpforms-3673-field_66-container\" class=\"wpforms-field wpforms-field-date-time wpforms-one-third wpforms-first\" data-field-id=\"66\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_66\">Employed from:<\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-3673-field_66\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-large\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][66][date]\" placeholder=\"Start Date\" ><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-3673-field_67-container\" class=\"wpforms-field wpforms-field-date-time wpforms-one-third wpforms-first\" data-field-id=\"67\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_67\">Employed until:<\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-3673-field_67\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-large\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][67][date]\" placeholder=\"End Date\" ><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-3673-field_82-container\" class=\"wpforms-field wpforms-field-captcha\" data-field-id=\"82\"><label class=\"wpforms-field-label\" for=\"wpforms-3673-field_82\">Custom Captcha <span class=\"wpforms-required-label\">*<\/span><\/label>\t\t\t<div class=\"wpforms-captcha-math\">\n\t\t\t\t<span id=\"wpforms-3673-field_82-question\" class=\"wpforms-captcha-equation\">\n\t\t\t\t\t<span class=\"n1\">6<\/span>\n\t\t\t\t\t\t\t<span class=\"cal\">*<\/span>\n\t\t\t\t\t\t\t<span class=\"n2\">9<\/span>\t\t\t\t\t<span class=\"e\">=<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<input type=\"text\" id=\"wpforms-3673-field_82\" class=\"wpforms-field-medium wpforms-field-required a\" data-rule-wpf-captcha=\"math\" data-is-wrapped-field=\"1\" name=\"wpforms[fields][82][a]\" aria-describedby=\"wpforms-3673-field_82-question\" required>\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][82][cal]\" class=\"cal\">\n\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][82][n2]\" class=\"n2\">\n\t\t\t\t<input type=\"hidden\" name=\"wpforms[fields][82][n1]\" class=\"n1\">\n\t\t\t<\/div>\n\t\t\t<\/div><div id=\"wpforms-3673-field_6-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"6\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><\/div><\/div><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-3673-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-3673-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-3673-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-invisible\" style=\"display:none;\"><div class=\"g-recaptcha\" data-sitekey=\"6LcIQ7IZAAAAAEaVjfei98NuEqEYOEXvDV9CnPl1\" data-size=\"invisible\"><\/div><\/div><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"3673\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/pages\/3660\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-3673\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-04f8394\" data-id=\"04f8394\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-416b1de elementor-widget elementor-widget-image\" data-id=\"416b1de\" data-element_type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" loading=\"\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"703\" height=\"1084\" src=\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2024\/09\/indeed-ad.jpg\" class=\"attachment-full size-full wp-image-6906\" alt=\"Indeed The Goldton At Adelaide\" srcset=\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2024\/09\/indeed-ad.jpg 703w, https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2024\/09\/indeed-ad-195x300.jpg 195w, https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2024\/09\/indeed-ad-664x1024.jpg 664w\" sizes=\"(max-width: 703px) 100vw, 703px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Start a Fulfilling Career at Senior Living Job Application If you are interested in working at The Goldton at Adelaide please complete the application below. We will contact you if your skills match any of our open positions. Please enable JavaScript in your browser to complete this form.About You &#8211; Step 1 of 2Job InterestYour [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":3617,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3660","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v26.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Senior Living Careers | The Goldton at Adelaide<\/title>\n<meta name=\"description\" content=\"Start a fulfilling career at Senior Living at The Goldton At Adelaide. Fill the form now.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Careers\" \/>\n<meta property=\"og:description\" content=\"Start a fulfilling career at Senior Living at The Goldton At Adelaide. Fill the form now.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/\" \/>\n<meta property=\"og:site_name\" content=\"Senior Living in Starkville MS | The Goldton at Adelaide\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheOscarAtGeorgetown\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-13T18:52:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2023\/06\/home-sweet-home-the-goldton-at-adelaide.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/\",\"url\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/\",\"name\":\"Senior Living Careers | The Goldton at Adelaide\",\"isPartOf\":{\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2023\/06\/home-sweet-home-the-goldton-at-adelaide.jpg\",\"datePublished\":\"2023-07-18T17:09:25+00:00\",\"dateModified\":\"2025-02-13T18:52:02+00:00\",\"description\":\"Start a fulfilling career at Senior Living at The Goldton At Adelaide. Fill the form now.\",\"breadcrumb\":{\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/#primaryimage\",\"url\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2023\/06\/home-sweet-home-the-goldton-at-adelaide.jpg\",\"contentUrl\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2023\/06\/home-sweet-home-the-goldton-at-adelaide.jpg\",\"width\":1536,\"height\":2048,\"caption\":\"Home Sweet Home, The Goldton at Adelaide\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Careers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#website\",\"url\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/\",\"name\":\"Senior Living in Starkville MS | The Goldton at Adelaide\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#organization\",\"name\":\"The Oscar at Georgetown\",\"url\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2022\/10\/Asset-3@300x.png\",\"contentUrl\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2022\/10\/Asset-3@300x.png\",\"width\":1102,\"height\":609,\"caption\":\"The Oscar at Georgetown\"},\"image\":{\"@id\":\"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TheOscarAtGeorgetown\",\"https:\/\/instagram.com\/oscargeorgetown\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Senior Living Careers | The Goldton at Adelaide","description":"Start a fulfilling career at Senior Living at The Goldton At Adelaide. Fill the form now.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/","og_locale":"en_US","og_type":"article","og_title":"Careers","og_description":"Start a fulfilling career at Senior Living at The Goldton At Adelaide. Fill the form now.","og_url":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/","og_site_name":"Senior Living in Starkville MS | The Goldton at Adelaide","article_publisher":"https:\/\/www.facebook.com\/TheOscarAtGeorgetown","article_modified_time":"2025-02-13T18:52:02+00:00","og_image":[{"width":1536,"height":2048,"url":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2023\/06\/home-sweet-home-the-goldton-at-adelaide.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/","url":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/","name":"Senior Living Careers | The Goldton at Adelaide","isPartOf":{"@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#website"},"primaryImageOfPage":{"@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/#primaryimage"},"image":{"@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/#primaryimage"},"thumbnailUrl":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2023\/06\/home-sweet-home-the-goldton-at-adelaide.jpg","datePublished":"2023-07-18T17:09:25+00:00","dateModified":"2025-02-13T18:52:02+00:00","description":"Start a fulfilling career at Senior Living at The Goldton At Adelaide. Fill the form now.","breadcrumb":{"@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/#primaryimage","url":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2023\/06\/home-sweet-home-the-goldton-at-adelaide.jpg","contentUrl":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2023\/06\/home-sweet-home-the-goldton-at-adelaide.jpg","width":1536,"height":2048,"caption":"Home Sweet Home, The Goldton at Adelaide"},{"@type":"BreadcrumbList","@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/careers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/"},{"@type":"ListItem","position":2,"name":"Careers"}]},{"@type":"WebSite","@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#website","url":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/","name":"Senior Living in Starkville MS | The Goldton at Adelaide","description":"","publisher":{"@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#organization","name":"The Oscar at Georgetown","url":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#\/schema\/logo\/image\/","url":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2022\/10\/Asset-3@300x.png","contentUrl":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-content\/uploads\/sites\/44\/2022\/10\/Asset-3@300x.png","width":1102,"height":609,"caption":"The Oscar at Georgetown"},"image":{"@id":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TheOscarAtGeorgetown","https:\/\/instagram.com\/oscargeorgetown"]}]}},"_links":{"self":[{"href":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/pages\/3660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/comments?post=3660"}],"version-history":[{"count":43,"href":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/pages\/3660\/revisions"}],"predecessor-version":[{"id":9327,"href":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/pages\/3660\/revisions\/9327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/media\/3617"}],"wp:attachment":[{"href":"https:\/\/atlasseniorliving.com\/the-goldton-at-adelaide\/wp-json\/wp\/v2\/media?parent=3660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}